{"id":42313,"date":"2023-08-11T20:07:01","date_gmt":"2023-08-11T18:07:01","guid":{"rendered":"https:\/\/laura4u.aboama.com\/prodotto\/il-primo-passo-sulla-luna\/"},"modified":"2023-08-11T20:07:01","modified_gmt":"2023-08-11T18:07:01","slug":"il-primo-passo-sulla-luna","status":"publish","type":"product","link":"https:\/\/laura4u.aboama.com\/en\/prodotto\/il-primo-passo-sulla-luna\/","title":{"rendered":"IL PRIMO PASSO SULLA LUNA"},"content":{"rendered":"<table width=\"503\">\n<thead>\n<tr>\n<td><strong>SIZE<\/strong><\/td>\n<td><strong>XS<\/strong><\/td>\n<td><strong>S<\/strong><\/td>\n<td><strong>M<\/strong><\/td>\n<td><strong>L<\/strong><\/td>\n<td><strong>XL<\/strong><\/td>\n<td><strong>XXL<\/strong><\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td><strong>HEIGHT<\/strong><\/td>\n<td>68<\/td>\n<td>70<\/td>\n<td>72<\/td>\n<td>74<\/td>\n<td>76<\/td>\n<td>78<\/td>\n<\/tr>\n<tr>\n<td><strong>WIDTH<\/strong><\/td>\n<td>47<\/td>\n<td>50<\/td>\n<td>53<\/td>\n<td>56<\/td>\n<td>59<\/td>\n<td>62<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Description: 100% cotton T-Shirt. Short sleeves, round neck, soft touch, tubular structure.<\/p>\n","protected":false},"featured_media":42057,"template":"","meta":[],"product_brand":[],"product_cat":[505],"product_tag":[],"class_list":["post-42313","product","type-product","status-publish","has-post-thumbnail","product_cat-venezia-sevilla-2023-en","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","wpzoom-wc-spi-has-enabled"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IL PRIMO PASSO SULLA LUNA - Laura4u<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laura4u.aboama.com\/en\/prodotto\/il-primo-passo-sulla-luna\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IL PRIMO PASSO SULLA LUNA - Laura4u\" \/>\n<meta property=\"og:description\" content=\"Description: 100% cotton T-Shirt. Short sleeves, round neck, soft touch, tubular structure.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laura4u.aboama.com\/en\/prodotto\/il-primo-passo-sulla-luna\/\" \/>\n<meta property=\"og:site_name\" content=\"Laura4u\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/prodotto\\\/il-primo-passo-sulla-luna\\\/\",\"url\":\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/prodotto\\\/il-primo-passo-sulla-luna\\\/\",\"name\":\"IL PRIMO PASSO SULLA LUNA - Laura4u\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/prodotto\\\/il-primo-passo-sulla-luna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/prodotto\\\/il-primo-passo-sulla-luna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/laura4u.aboama.com\\\/wp-content\\\/uploads\\\/sites\\\/39\\\/2023\\\/08\\\/FRONTE-8.jpg\",\"datePublished\":\"2023-08-11T18:07:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/prodotto\\\/il-primo-passo-sulla-luna\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/prodotto\\\/il-primo-passo-sulla-luna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/prodotto\\\/il-primo-passo-sulla-luna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/laura4u.aboama.com\\\/wp-content\\\/uploads\\\/sites\\\/39\\\/2023\\\/08\\\/FRONTE-8.jpg\",\"contentUrl\":\"https:\\\/\\\/laura4u.aboama.com\\\/wp-content\\\/uploads\\\/sites\\\/39\\\/2023\\\/08\\\/FRONTE-8.jpg\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/prodotto\\\/il-primo-passo-sulla-luna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/pagina-di-esempio-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IL PRIMO PASSO SULLA LUNA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/\",\"name\":\"Laura4u\",\"description\":\"Ink Printed In Italy\",\"publisher\":{\"@id\":\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/#organization\",\"name\":\"Laura4u\",\"url\":\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/laura4u.aboama.com\\\/wp-content\\\/uploads\\\/sites\\\/39\\\/2022\\\/07\\\/cropped-LP-official-merch-copia-600x322-1.png\",\"contentUrl\":\"https:\\\/\\\/laura4u.aboama.com\\\/wp-content\\\/uploads\\\/sites\\\/39\\\/2022\\\/07\\\/cropped-LP-official-merch-copia-600x322-1.png\",\"width\":600,\"height\":322,\"caption\":\"Laura4u\"},\"image\":{\"@id\":\"https:\\\/\\\/laura4u.aboama.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IL PRIMO PASSO SULLA LUNA - Laura4u","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laura4u.aboama.com\/en\/prodotto\/il-primo-passo-sulla-luna\/","og_locale":"en_US","og_type":"article","og_title":"IL PRIMO PASSO SULLA LUNA - Laura4u","og_description":"Description: 100% cotton T-Shirt. Short sleeves, round neck, soft touch, tubular structure.","og_url":"https:\/\/laura4u.aboama.com\/en\/prodotto\/il-primo-passo-sulla-luna\/","og_site_name":"Laura4u","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/laura4u.aboama.com\/en\/prodotto\/il-primo-passo-sulla-luna\/","url":"https:\/\/laura4u.aboama.com\/en\/prodotto\/il-primo-passo-sulla-luna\/","name":"IL PRIMO PASSO SULLA LUNA - Laura4u","isPartOf":{"@id":"https:\/\/laura4u.aboama.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/laura4u.aboama.com\/en\/prodotto\/il-primo-passo-sulla-luna\/#primaryimage"},"image":{"@id":"https:\/\/laura4u.aboama.com\/en\/prodotto\/il-primo-passo-sulla-luna\/#primaryimage"},"thumbnailUrl":"https:\/\/laura4u.aboama.com\/wp-content\/uploads\/sites\/39\/2023\/08\/FRONTE-8.jpg","datePublished":"2023-08-11T18:07:01+00:00","breadcrumb":{"@id":"https:\/\/laura4u.aboama.com\/en\/prodotto\/il-primo-passo-sulla-luna\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/laura4u.aboama.com\/en\/prodotto\/il-primo-passo-sulla-luna\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/laura4u.aboama.com\/en\/prodotto\/il-primo-passo-sulla-luna\/#primaryimage","url":"https:\/\/laura4u.aboama.com\/wp-content\/uploads\/sites\/39\/2023\/08\/FRONTE-8.jpg","contentUrl":"https:\/\/laura4u.aboama.com\/wp-content\/uploads\/sites\/39\/2023\/08\/FRONTE-8.jpg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/laura4u.aboama.com\/en\/prodotto\/il-primo-passo-sulla-luna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/laura4u.aboama.com\/en\/pagina-di-esempio-2\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/laura4u.aboama.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"IL PRIMO PASSO SULLA LUNA"}]},{"@type":"WebSite","@id":"https:\/\/laura4u.aboama.com\/en\/#website","url":"https:\/\/laura4u.aboama.com\/en\/","name":"Laura4u","description":"Ink Printed In Italy","publisher":{"@id":"https:\/\/laura4u.aboama.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laura4u.aboama.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/laura4u.aboama.com\/en\/#organization","name":"Laura4u","url":"https:\/\/laura4u.aboama.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/laura4u.aboama.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/laura4u.aboama.com\/wp-content\/uploads\/sites\/39\/2022\/07\/cropped-LP-official-merch-copia-600x322-1.png","contentUrl":"https:\/\/laura4u.aboama.com\/wp-content\/uploads\/sites\/39\/2022\/07\/cropped-LP-official-merch-copia-600x322-1.png","width":600,"height":322,"caption":"Laura4u"},"image":{"@id":"https:\/\/laura4u.aboama.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/laura4u.aboama.com\/en\/wp-json\/wp\/v2\/product\/42313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laura4u.aboama.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/laura4u.aboama.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laura4u.aboama.com\/en\/wp-json\/wp\/v2\/media\/42057"}],"wp:attachment":[{"href":"https:\/\/laura4u.aboama.com\/en\/wp-json\/wp\/v2\/media?parent=42313"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/laura4u.aboama.com\/en\/wp-json\/wp\/v2\/product_brand?post=42313"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/laura4u.aboama.com\/en\/wp-json\/wp\/v2\/product_cat?post=42313"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/laura4u.aboama.com\/en\/wp-json\/wp\/v2\/product_tag?post=42313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}